{"id":15940,"date":"2022-01-26T18:09:06","date_gmt":"2022-01-26T17:09:06","guid":{"rendered":"https:\/\/www.erea86.fr\/version2\/?p=15940"},"modified":"2022-01-26T20:47:42","modified_gmt":"2022-01-26T19:47:42","slug":"en-terra-aventura-a-saint-benoit","status":"publish","type":"post","link":"https:\/\/www.erea86.fr\/version2\/2022\/01\/26\/en-terra-aventura-a-saint-benoit\/","title":{"rendered":"En T\u00e8rra Aventura \u00e0 Saint-Benoit"},"content":{"rendered":"<p>Ce mercredi 26 janvier, nous avons brav\u00e9 le froid dans Saint-Benoit.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15944 size-large\" src=\"https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_143045-1024x461.jpg\" alt=\"\" width=\"640\" height=\"288\" srcset=\"https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_143045-1024x461.jpg 1024w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_143045-300x135.jpg 300w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_143045-768x346.jpg 768w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_143045-1536x691.jpg 1536w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_143045-2048x922.jpg 2048w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_143045-360x162.jpg 360w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Le jeu<a href=\"https:\/\/www.terra-aventura.fr\/\" target=\"_blank\" rel=\"noopener\"> Terr\u00e0 Aventura<\/a> nous a permis de r\u00e9soudre des \u00e9nigmes en parcourant le village.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15957 \" src=\"https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_142429-173x300.jpg\" alt=\"\" width=\"214\" height=\"371\" srcset=\"https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_142429-173x300.jpg 173w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_142429-589x1024.jpg 589w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_142429-768x1334.jpg 768w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_142429-884x1536.jpg 884w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_142429-1179x2048.jpg 1179w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_142429-155x270.jpg 155w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_142429-scaled.jpg 1473w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/p>\n<p>Nous avons ainsi visit\u00e9 les parcs, le viaduc, le panneau solaire, l&rsquo;abbaye et son prieur\u00e9&#8230; et avons finalement d\u00e9couvert le tr\u00e9sor final. \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15947 size-large\" src=\"https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_154914-scaled-e1643218149742-931x1024.jpg\" alt=\"\" width=\"640\" height=\"704\" srcset=\"https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_154914-scaled-e1643218149742-931x1024.jpg 931w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_154914-scaled-e1643218149742-273x300.jpg 273w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_154914-scaled-e1643218149742-768x845.jpg 768w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_154914-scaled-e1643218149742-245x270.jpg 245w, https:\/\/www.erea86.fr\/version2\/wp-content\/uploads\/2022\/01\/IMG_20220126_154914-scaled-e1643218149742.jpg 1152w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce mercredi 26 janvier, nous avons brav\u00e9 le froid dans Saint-Benoit. Le jeu Terr\u00e0 Aventura nous a permis de r\u00e9soudre des \u00e9nigmes en parcourant le&hellip;&nbsp;<a href=\"https:\/\/www.erea86.fr\/version2\/2022\/01\/26\/en-terra-aventura-a-saint-benoit\/\" class=\"more-link\">Lire la suite<\/a><\/p>\n","protected":false},"author":219,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[42,5],"tags":[],"class_list":["post-15940","post","type-post","status-publish","format-standard","hentry","category-activites","category-educatif"],"_links":{"self":[{"href":"https:\/\/www.erea86.fr\/version2\/wp-json\/wp\/v2\/posts\/15940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erea86.fr\/version2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erea86.fr\/version2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erea86.fr\/version2\/wp-json\/wp\/v2\/users\/219"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erea86.fr\/version2\/wp-json\/wp\/v2\/comments?post=15940"}],"version-history":[{"count":9,"href":"https:\/\/www.erea86.fr\/version2\/wp-json\/wp\/v2\/posts\/15940\/revisions"}],"predecessor-version":[{"id":15972,"href":"https:\/\/www.erea86.fr\/version2\/wp-json\/wp\/v2\/posts\/15940\/revisions\/15972"}],"wp:attachment":[{"href":"https:\/\/www.erea86.fr\/version2\/wp-json\/wp\/v2\/media?parent=15940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erea86.fr\/version2\/wp-json\/wp\/v2\/categories?post=15940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erea86.fr\/version2\/wp-json\/wp\/v2\/tags?post=15940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}